{"id":8391,"date":"2026-07-07T14:05:52","date_gmt":"2026-07-07T17:05:52","guid":{"rendered":"https:\/\/abics.com.br\/?p=8391"},"modified":"2026-07-07T14:07:09","modified_gmt":"2026-07-07T17:07:09","slug":"cafe-soluvel-esperancoso-audiencia-ustr-taxas","status":"publish","type":"post","link":"https:\/\/abics.com.br\/en\/cafe-soluvel-esperancoso-audiencia-ustr-taxas\/","title":{"rendered":"Caf\u00e9 sol\u00favel brasileiro sai esperan\u00e7oso de audi\u00eancia do USTR sobre taxas de 25%"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Setor foi defendido por Abics, Cecaf\u00e9 e NCA, que refor\u00e7aram a import\u00e2ncia do produto nacional \u00e0 cadeia cafeeira norte-americana, al\u00e9m da infla\u00e7\u00e3o que uma taxa\u00e7\u00e3o imporia aos bolsos da popula\u00e7\u00e3o<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Associa\u00e7\u00e3o Brasileira da Ind\u00fastria de Caf\u00e9 Sol\u00favel (Abics), representada pelo escrit\u00f3rio contratado BMJ Consultores Associados, participou, ontem (6) e hoje (7), em Washington, nos EUA, junto a representantes de diversos setores da economia nacional, das audi\u00eancias p\u00fablicas do Escrit\u00f3rio do Representante Comercial dos Estados Unidos (USTR, em ingl\u00eas) sobre a proposta norte-americana de sobretaxar produtos exportados pelo Brasil em 25%, incluindo o caf\u00e9 sol\u00favel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em sua participa\u00e7\u00e3o, realizada ontem, a entidade exp\u00f4s que o produto \u00e9 um insumo fundamental para diversos setores da economia dos EUA, incluindo bebidas prontas para consumo, produtos de panifica\u00e7\u00e3o, confeitaria, latic\u00ednios e servi\u00e7os de alimenta\u00e7\u00e3o institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com estudos que apontam um crescimento anual de 5,6% entre 2025 e 2030 no mercado norte-americano de caf\u00e9 pronto para consumo \u2013 <em>ready to drink<\/em> \u2013 , a Abics salientou a necessidade de um abastecimento est\u00e1vel e acess\u00edvel do caf\u00e9 sol\u00favel brasileiro, insumo essencial para esse produto no mercado dos EUA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Associa\u00e7\u00e3o completou que grandes empresas americanas de alimentos e bebidas, incluindo as que representam mais de 20% das vendas de caf\u00e9 no varejo dom\u00e9stico e mais de 10% do consumo total de caf\u00e9, tamb\u00e9m dependem de um fornecimento est\u00e1vel de caf\u00e9 sol\u00favel para manter suas opera\u00e7\u00f5es e estrat\u00e9gias de pre\u00e7os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, a entidade refor\u00e7ou que o Brasil desempenha um papel indispens\u00e1vel na cadeia de suprimentos dos Estados Unidos, tendo respondido por 22% das importa\u00e7\u00f5es norte-americanas de caf\u00e9 sol\u00favel \u2013 totalizando 15.500 toneladas m\u00e9tricas \u2013, principalmente na forma de extratos a granel, concentrados e gr\u00e2nulos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Abics tamb\u00e9m recordou que o caf\u00e9 sol\u00favel brasileiro oferece perfis de solubilidade \u00fanicos, misturas de origem geogr\u00e1fica espec\u00edfica e certifica\u00e7\u00f5es de qualidade reconhecidas internacionalmente que n\u00e3o podem ser efetivamente replicadas por outros fornecedores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro ponto apresentado foi que essa cadeia de suprimentos afeta diretamente os consumidores norte-americanos, uma vez que 11% da popula\u00e7\u00e3o local consomem caf\u00e9 sol\u00favel diariamente, a um custo de apenas US$ 0,06 a US$ 0,07 por x\u00edcara, especialmente em fam\u00edlias preocupadas com a quest\u00e3o or\u00e7ament\u00e1ria. Assim, a entidade argumentou que uma tarifa adicional de 25% (nos termos da Se\u00e7\u00e3o 301) elevaria os pre\u00e7os, pressionaria as margens das empresas e sobrecarregaria desproporcionalmente as fam\u00edlias que dependem de caf\u00e9 acess\u00edvel para consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl\u00e9m disso, esse suprimento n\u00e3o pode ser facilmente substitu\u00eddo. O mercado de importa\u00e7\u00e3o de caf\u00e9 sol\u00favel dos EUA \u00e9 altamente concentrado: M\u00e9xico e Brasil respondem por quase 60% do total das importa\u00e7\u00f5es, sendo que os pre\u00e7os mexicanos s\u00e3o cerca de 1,5 vez mais altos que os brasileiros\u201d, explica o diretor de Rela\u00e7\u00f5es Institucionais da Abics, Fabio Sato, que esteve presente na audi\u00eancia e completa que, \u201ccom capacidade excedente limitada na Col\u00f4mbia, no Vietn\u00e3 e na Indon\u00e9sia, fornecedores alternativos n\u00e3o conseguem suprir essa lacuna prontamente\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele lembra que, igualmente importante \u00e9 o fato de que o caf\u00e9 sol\u00favel brasileiro segue rigorosos padr\u00f5es de qualidade da Abics, incluindo as classifica\u00e7\u00f5es \u201cClassic\u201d, \u201cPremium\u201d, \u201cExcellence\u201d e \u201c100% Ar\u00e1bica\u201d e que a implanta\u00e7\u00e3o de tarifas adicionais provocaria escassez imediata, custos mais elevados, menor qualidade e redu\u00e7\u00e3o da competitividade em todo o mercado dos EUA, prejudicando fabricantes, operadores de servi\u00e7os de alimenta\u00e7\u00e3o e consumidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA maior parte do valor econ\u00f4mico desse com\u00e9rcio \u00e9 gerada nos Estados Unidos. O caf\u00e9 sol\u00favel brasileiro entra quase inteiramente a granel, enquanto a mistura, o empacotamento, o marketing e a distribui\u00e7\u00e3o ocorrem em solo americano. Portanto, uma tarifa sobre esse produto n\u00e3o penalizaria um bem estrangeiro acabado, mas aumentaria os custos para os fabricantes nacionais e enfraqueceria a competitividade dos produtos de caf\u00e9 sol\u00favel fabricados nos EUA\u201d, analisa Sato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o diretor da Abics, as implica\u00e7\u00f5es log\u00edsticas tamb\u00e9m s\u00e3o significativas, com mais de 81% das importa\u00e7\u00f5es de caf\u00e9 sol\u00favel dos EUA entrando por Texas, Nova York e Louisiana, enquanto as remessas brasileiras s\u00e3o concentradas em Nova Orleans, Nova York, Charleston e Los Angeles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUma queda acentuada na oferta brasileira afetaria centros log\u00edsticos importantes na Costa do Golfo e no Nordeste, gerando escassez e colocando em risco as opera\u00e7\u00f5es industriais\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda em sua explana\u00e7\u00e3o, os representantes da Abics refor\u00e7aram que tarifas sobre o caf\u00e9 sol\u00favel n\u00e3o seriam pr\u00e1ticas nem eficazes para promover os objetivos da investiga\u00e7\u00e3o do USTR, recordando que o com\u00e9rcio de caf\u00e9 opera dentro de um sistema agr\u00edcola transparente e orientado pelo mercado, distinto das quest\u00f5es de com\u00e9rcio digital, propriedade intelectual, meio ambiente e pr\u00e1ticas de pagamento que est\u00e3o sob an\u00e1lise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A entidade tamb\u00e9m advertiu que aumentos tarif\u00e1rios anteriores demonstraram que choques repentinos de custos reduzem os volumes de importa\u00e7\u00e3o, perturbam as cadeias de suprimentos e elevam rapidamente os pre\u00e7os ao consumidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDadas as margens reduzidas dos produtores de alimentos e bebidas dos EUA, esses custos provavelmente seriam repassados \u200b\u200baos consumidores, gerando disparada na infla\u00e7\u00e3o. Por todas essas raz\u00f5es, solicitamos ao USTR a exclus\u00e3o do c\u00f3digo HTS 2101.11.21, que se refere ao caf\u00e9 sol\u00favel brasileiro, de quaisquer tarifas adicionais da Se\u00e7\u00e3o 301\u201d, informa Sato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 o diretor de Rela\u00e7\u00f5es Governamentais e Com\u00e9rcio Internacional do BMJ, Jos\u00e9 Pimenta, comunica que, al\u00e9m da Abics, a defesa do caf\u00e9 sol\u00favel brasileiro tamb\u00e9m foi feita pelo Conselho dos Exportadores de Caf\u00e9 do Brasil (Cecaf\u00e9) e pela entidade par norte-americana <em>National Coffee Association<\/em> (NCA), gerando 15 minutos de defesa na audi\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs tr\u00eas manifesta\u00e7\u00f5es conversavam muito entre si e um ponto importante \u00e9 que nenhuma das entidades foi arguida, n\u00e3o houve contesta\u00e7\u00e3o em nenhum dos pronunciamentos de defesa do caf\u00e9 sol\u00favel brasileiro, o que nos deixa esperan\u00e7osos para que o produto n\u00e3o venha a sofrer a taxa\u00e7\u00e3o de 25%, entrando em uma lista de isen\u00e7\u00e3o, tal qual os demais tipos de caf\u00e9 do Brasil\u201d, relata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pimenta acresce que, na parte da audi\u00eancia aberta aos questionamentos dos investigadores americanos, as perguntas focaram a quest\u00e3o mais espec\u00edfica do eventual impacto tarif\u00e1rio para a cadeia de caf\u00e9 dos EUA como um todo, em especial ao <em>manufacturing<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIsso foi positivo, pois pudemos refor\u00e7ar todo o impacto econ\u00f4mico e tamb\u00e9m social que a adi\u00e7\u00e3o de tarifas de 25% ao caf\u00e9 sol\u00favel brasileiro gerar\u00e1 na economia americana e nos bolsos de seus consumidores\u201d, conclui o diretor do BMJ.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes de Cecaf\u00e9 (Marcos Matos), Abics, NCA (Bill Murray) e BMJ defenderam o setor na audi\u00eancia.<\/p>\n","protected":false},"author":3,"featured_media":8392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[139,137,134,133],"class_list":["post-8391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cecafe","tag-nca","tag-tarifaco","tag-ustr"],"_links":{"self":[{"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/posts\/8391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/comments?post=8391"}],"version-history":[{"count":1,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/posts\/8391\/revisions"}],"predecessor-version":[{"id":8396,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/posts\/8391\/revisions\/8396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/media\/8392"}],"wp:attachment":[{"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/media?parent=8391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/categories?post=8391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abics.com.br\/en\/wp-json\/wp\/v2\/tags?post=8391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}